{"id":52,"count":3,"description":"Die Kategorie f\u00fcr Beitr\u00e4ge \u00fcber alte Gottheiten in heutiger Zeit, \u00fcber modernes Heidentum","link":"https:\/\/beowulf-shop.de\/blog\/category\/modernes-heidentum\/","name":"Modernes Heidentum","slug":"modernes-heidentum","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Modernes Heidentum Archive - Beowulf Blog<\/title>\n<meta name=\"description\" content=\"Die Kategorie f\u00fcr Beitr\u00e4ge \u00fcber alte Gottheiten in heutiger Zeit, \u00fcber modernes Heidentum\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beowulf-shop.de\/blog\/category\/modernes-heidentum\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modernes Heidentum Archive - Beowulf Blog\" \/>\n<meta property=\"og:description\" content=\"Die Kategorie f\u00fcr Beitr\u00e4ge \u00fcber alte Gottheiten in heutiger Zeit, \u00fcber modernes Heidentum\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beowulf-shop.de\/blog\/category\/modernes-heidentum\/\" \/>\n<meta property=\"og:site_name\" content=\"Beowulf Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/beowulf-shop.de\/blog\/category\/modernes-heidentum\/\",\"url\":\"https:\/\/beowulf-shop.de\/blog\/category\/modernes-heidentum\/\",\"name\":\"Modernes Heidentum Archive - Beowulf Blog\",\"isPartOf\":{\"@id\":\"https:\/\/beowulf-shop.de\/blog\/#website\"},\"description\":\"Die Kategorie f\u00fcr Beitr\u00e4ge \u00fcber alte Gottheiten in heutiger Zeit, \u00fcber modernes Heidentum\",\"breadcrumb\":{\"@id\":\"https:\/\/beowulf-shop.de\/blog\/category\/modernes-heidentum\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/beowulf-shop.de\/blog\/category\/modernes-heidentum\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/beowulf-shop.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Modernes Heidentum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/beowulf-shop.de\/blog\/#website\",\"url\":\"https:\/\/beowulf-shop.de\/blog\/\",\"name\":\"Beowulf Blog, das Blog vom Beowulf-Shop\",\"description\":\"Das Blog vom Beowulf-Shop\",\"publisher\":{\"@id\":\"https:\/\/beowulf-shop.de\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/beowulf-shop.de\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/beowulf-shop.de\/blog\/#organization\",\"name\":\"Beowulf Schleswig\",\"url\":\"https:\/\/beowulf-shop.de\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/beowulf-shop.de\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/beowulf-shop.de\/blog\/wp-content\/uploads\/2023\/01\/Boot-Gruenrunen-trans.png\",\"contentUrl\":\"https:\/\/beowulf-shop.de\/blog\/wp-content\/uploads\/2023\/01\/Boot-Gruenrunen-trans.png\",\"width\":2762,\"height\":1429,\"caption\":\"Beowulf Schleswig\"},\"image\":{\"@id\":\"https:\/\/beowulf-shop.de\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/de-de.facebook.com\/BeowulfSchleswig\",\"https:\/\/www.youtube.com\/channel\/UCQILicznNdKo_qn4MUE09rg\",\"https:\/\/www.instagram.com\/beowulf_schleswig\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Modernes Heidentum Archive - Beowulf Blog","description":"Die Kategorie f\u00fcr Beitr\u00e4ge \u00fcber alte Gottheiten in heutiger Zeit, \u00fcber modernes Heidentum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beowulf-shop.de\/blog\/category\/modernes-heidentum\/","og_locale":"de_DE","og_type":"article","og_title":"Modernes Heidentum Archive - Beowulf Blog","og_description":"Die Kategorie f\u00fcr Beitr\u00e4ge \u00fcber alte Gottheiten in heutiger Zeit, \u00fcber modernes Heidentum","og_url":"https:\/\/beowulf-shop.de\/blog\/category\/modernes-heidentum\/","og_site_name":"Beowulf Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/beowulf-shop.de\/blog\/category\/modernes-heidentum\/","url":"https:\/\/beowulf-shop.de\/blog\/category\/modernes-heidentum\/","name":"Modernes Heidentum Archive - Beowulf Blog","isPartOf":{"@id":"https:\/\/beowulf-shop.de\/blog\/#website"},"description":"Die Kategorie f\u00fcr Beitr\u00e4ge \u00fcber alte Gottheiten in heutiger Zeit, \u00fcber modernes Heidentum","breadcrumb":{"@id":"https:\/\/beowulf-shop.de\/blog\/category\/modernes-heidentum\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/beowulf-shop.de\/blog\/category\/modernes-heidentum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/beowulf-shop.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Modernes Heidentum"}]},{"@type":"WebSite","@id":"https:\/\/beowulf-shop.de\/blog\/#website","url":"https:\/\/beowulf-shop.de\/blog\/","name":"Beowulf Blog, das Blog vom Beowulf-Shop","description":"Das Blog vom Beowulf-Shop","publisher":{"@id":"https:\/\/beowulf-shop.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beowulf-shop.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/beowulf-shop.de\/blog\/#organization","name":"Beowulf Schleswig","url":"https:\/\/beowulf-shop.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/beowulf-shop.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/beowulf-shop.de\/blog\/wp-content\/uploads\/2023\/01\/Boot-Gruenrunen-trans.png","contentUrl":"https:\/\/beowulf-shop.de\/blog\/wp-content\/uploads\/2023\/01\/Boot-Gruenrunen-trans.png","width":2762,"height":1429,"caption":"Beowulf Schleswig"},"image":{"@id":"https:\/\/beowulf-shop.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/de-de.facebook.com\/BeowulfSchleswig","https:\/\/www.youtube.com\/channel\/UCQILicznNdKo_qn4MUE09rg","https:\/\/www.instagram.com\/beowulf_schleswig\/"]}]}},"_links":{"self":[{"href":"https:\/\/beowulf-shop.de\/blog\/wp-json\/wp\/v2\/categories\/52","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beowulf-shop.de\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/beowulf-shop.de\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/beowulf-shop.de\/blog\/wp-json\/wp\/v2\/posts?categories=52"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}